{"id":14707,"date":"2026-07-14T09:39:19","date_gmt":"2026-07-14T07:39:19","guid":{"rendered":"https:\/\/www.iwim.it\/logiciel-integre-pour-surveiller-le-trafic-et-letat-des-infrastructures-avec-bison-et-grifone\/"},"modified":"2026-07-14T09:39:20","modified_gmt":"2026-07-14T07:39:20","slug":"logiciel-integre-pour-surveiller-le-trafic-et-letat-des-infrastructures-avec-bison-et-grifone","status":"publish","type":"post","link":"https:\/\/www.iwim.it\/fr\/logiciel-integre-pour-surveiller-le-trafic-et-letat-des-infrastructures-avec-bison-et-grifone\/","title":{"rendered":"Logiciel int\u00e9gr\u00e9 pour surveiller le trafic et l\u2019\u00e9tat des infrastructures avec BISON et GRIFONE"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"14707\" class=\"elementor elementor-14707 elementor-14601\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a6d834e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a6d834e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a5886cd\" data-id=\"a5886cd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0c1ea11 elementor-widget elementor-widget-heading\" data-id=\"0c1ea11\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Une plateforme flexible qui combine pes\u00e9e dynamique, surveillance structurelle et donn\u00e9es op\u00e9rationnelles en une interface unique.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8d99a67 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8d99a67\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-74961dd\" data-id=\"74961dd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0a3f6c2 elementor-widget elementor-widget-heading\" data-id=\"0a3f6c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">iWIM d\u00e9veloppe non seulement le mat\u00e9riel, mais l\u2019ensemble de l\u2019\u00e9cosyst\u00e8me n\u00e9cessaire pour capturer, traiter, visualiser, exporter et comprendre les donn\u00e9es.  <\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-511ce80 elementor-widget elementor-widget-text-editor\" data-id=\"511ce80\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Depuis la cr\u00e9ation de l\u2019iWIM, le d\u00e9veloppement logiciel est une part fondamentale de nos syst\u00e8mes. Pour nous, il ne suffit pas qu\u2019une solution capture correctement les donn\u00e9es : il est tout aussi important que ces informations soient transmises, organis\u00e9es et affich\u00e9es de mani\u00e8re <strong data-start=\"545\" data-end=\"594\">claire, logique et imm\u00e9diatement compr\u00e9hensible<\/strong>. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-315213b elementor-widget elementor-widget-text-editor\" data-id=\"315213b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"PDq2pG_selectionAnchorContainer\" data-start=\"993\" data-end=\"1341\">Pour r\u00e9pondre \u00e0 ces besoins, i<strong>WIM a d\u00e9velopp\u00e9 en interne une plateforme logicielle<\/strong> accessible via une interface web, qui peut \u00eatre utilis\u00e9e depuis diff\u00e9rents appareils et adaptable aux besoins op\u00e9rationnels de chaque client. Le syst\u00e8me permet \u00e9galement d\u2019exporter et d\u2019int\u00e9grer des donn\u00e9es dans des bases de donn\u00e9es, des plateformes de gestion et des logiciels tiers. <\/p><p data-start=\"1343\" data-end=\"1748\">Avec l\u2019introduction de <strong>GRIFONE, le<\/strong> syst\u00e8me de surveillance <strong>structurelle<\/strong> par fibre optique int\u00e9gr\u00e9 \u00e0 BISONTE, le volume et la complexit\u00e9 des informations disponibles ont consid\u00e9rablement augment\u00e9. En effet, en plus des donn\u00e9es relatives aux v\u00e9hicules, il existe des \u00e9l\u00e9ments concernant la v\u00e9ritable r\u00e9ponse de l\u2019infrastructure : d\u00e9formations, inclinaisons, vibrations, d\u00e9placements, temp\u00e9rature et autres param\u00e8tres structurels. <\/p><p data-start=\"1750\" data-end=\"2036\"><strong>La synchronisation entre les deux syst\u00e8mes permet d\u2019associer chaque transit v\u00e9hiculaire \u00e0 la r\u00e9ponse enregistr\u00e9e par le tablier<\/strong> en m\u00eame temps, rendant visible la relation de cause \u00e0 effet entre la charge de trafic et le comportement de l\u2019\u0153uvre.<\/p><p data-start=\"2038\" data-end=\"2432\"><strong>Pour cette raison, l\u2019iWIM a r\u00e9alis\u00e9 au cours de l\u2019ann\u00e9e \u00e9coul\u00e9e une mise \u00e0 jour majeure de sa plateforme,<\/strong> \u00e9largissant l\u2019interface d\u00e9di\u00e9e aux <strong data-start=\"2184\" data-end=\"2217\">logiciels de pes\u00e9e dynamique<\/strong> et introduisant de nouveaux tableaux de bord pour <strong data-start=\"2256\" data-end=\"2284\">la surveillance structurelle<\/strong>. L\u2019objectif est de maintenir une lecture simple et imm\u00e9diate m\u00eame lorsque le syst\u00e8me g\u00e8re de grandes quantit\u00e9s de donn\u00e9es provenant de sources diff\u00e9rentes. <\/p><p data-start=\"2704\" data-end=\"2975\">Les clients ayant un contrat de maintenance peuvent \u00e9galement b\u00e9n\u00e9ficier <strong data-start=\"2786\" data-end=\"2870\">de mises \u00e0 jour continues, de nouvelles fonctionnalit\u00e9s, de mises \u00e0 jour et de personnalisations d\u00e9di\u00e9es<\/strong>, d\u00e9velopp\u00e9es selon les caract\u00e9ristiques du projet et les processus op\u00e9rationnels de chaque op\u00e9rateur.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-85be5fa elementor-widget elementor-widget-heading\" data-id=\"85be5fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Interface mise \u00e0 jour du logiciel de pes\u00e9e dynamique BISON<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-86df178 elementor-widget elementor-widget-heading\" data-id=\"86df178\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Toutes les donn\u00e9es de chaque transit dans une vue claire et imm\u00e9diate<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f561512 elementor-widget elementor-widget-text-editor\" data-id=\"f561512\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"3138\" data-end=\"3355\">L\u2019une des principales mises \u00e0 jour concerne le <b>tableau de bord en temps r\u00e9el<\/b>, con\u00e7u pour repr\u00e9senter chaque transit de v\u00e9hicule via une combinaison intuitive de tuiles, ic\u00f4nes, indicateurs et informations graphiques.<\/p><p data-start=\"3357\" data-end=\"3396\">L\u2019utilisateur peut imm\u00e9diatement consulter :<\/p><ul><li data-section-id=\"12ryy3d\" data-start=\"3398\" data-end=\"3456\"><strong data-start=\"3400\" data-end=\"3456\">identification du v\u00e9hicule, date et heure de transit ;<\/strong><\/li><li data-section-id=\"djuj0b\" data-start=\"3457\" data-end=\"3504\"><strong data-start=\"3459\" data-end=\"3504\">Pays ou nationalit\u00e9 associ\u00e9 au v\u00e9hicule ;<\/strong><\/li><li data-section-id=\"1vbu07c\" data-start=\"3505\" data-end=\"3546\"><strong data-start=\"3507\" data-end=\"3546\">nombre et configuration des axes ;<\/strong><\/li><li data-section-id=\"18ycr2i\" data-start=\"3547\" data-end=\"3586\"><strong data-start=\"3549\" data-end=\"3586\">le poids total mesur\u00e9 par le syst\u00e8me ;<\/strong><\/li><li data-section-id=\"850eop\" data-start=\"3587\" data-end=\"3641\"><strong data-start=\"3589\" data-end=\"3641\">le poids mesur\u00e9 sur des essieux individuels ou des groupes d\u2019essieux ;<\/strong><\/li><li data-section-id=\"1sfewx5\" data-start=\"3642\" data-end=\"3685\"><strong data-start=\"3644\" data-end=\"3685\">la vitesse et l\u2019acc\u00e9l\u00e9ration du v\u00e9hicule ;<\/strong><\/li><li data-section-id=\"pry6in\" data-start=\"3686\" data-end=\"3732\"><strong data-start=\"3688\" data-end=\"3732\">la direction de circulation et la voie utilis\u00e9e ;<\/strong><\/li><li data-section-id=\"1703ap6\" data-start=\"3733\" data-end=\"3780\"><strong data-start=\"3735\" data-end=\"3780\">taille et classification du v\u00e9hicule ;<\/strong><\/li><li data-section-id=\"136jivr\" data-start=\"3781\" data-end=\"3837\"><strong data-start=\"3783\" data-end=\"3837\">pourcentage de surcharge et r\u00e9sultats de transit ;<\/strong><\/li><li data-section-id=\"1xefxg4\" data-start=\"3838\" data-end=\"3897\"><strong data-start=\"3840\" data-end=\"3897\">statut du trafic, anomalies \u00e9ventuelles et valeur ESAL<\/strong><\/li><li data-section-id=\"1xefxg4\" data-start=\"3838\" data-end=\"3897\"><strong data-start=\"3840\" data-end=\"3897\"> <\/strong><\/li><\/ul><div><p data-start=\"3899\" data-end=\"4177\">Les informations sont organis\u00e9es de mani\u00e8re \u00e0 offrir une lecture rapide m\u00eame lors du contr\u00f4le op\u00e9rationnel en temps r\u00e9el. L\u2019interface peut \u00eatre utilis\u00e9e aussi bien par des utilisateurs techniques que par des op\u00e9rateurs qui ne poss\u00e8dent pas de comp\u00e9tences sp\u00e9cialis\u00e9es dans le domaine de la pes\u00e9e dynamique. <\/p><p data-start=\"4179\" data-end=\"4452\">Le tableau de bord facilite donc la v\u00e9rification de ce qui se passe sur la route, l\u2019identification des v\u00e9hicules surcharg\u00e9s et l\u2019acc\u00e8s rapide aux informations n\u00e9cessaires au contr\u00f4le du trafic et \u00e0 la gestion des infrastructures.<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fc9a231 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fc9a231\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-41b4820\" data-id=\"41b4820\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-86f9e98 elementor-widget elementor-widget-heading\" data-id=\"86f9e98\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">L\u2019\u00e9cran montre la d\u00e9tection en temps r\u00e9el d\u2019un v\u00e9hicule l\u00e9ger, avec les principaux param\u00e8tres li\u00e9s \u00e0 la vitesse, au poids, au nombre d\u2019essieux, \u00e0 la direction et au r\u00e9sultat du transit.<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c5d79d elementor-widget elementor-widget-image\" data-id=\"5c5d79d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"385\" src=\"https:\/\/www.iwim.it\/wp-content\/uploads\/2026\/06\/Immagine-2026-06-17-173336-1024x493.webp\" class=\"attachment-large size-large wp-image-14708\" alt=\"Capture d\u2019\u00e9cran du tableau de bord BISON en temps r\u00e9el avec les donn\u00e9es d\u2019un v\u00e9hicule l\u00e9ger : poids 2000 kg, vitesse 73 km\/h, 2 essieux, direction est, classe voiture\/fourgonnette et r\u00e9sultats NL.\" srcset=\"https:\/\/www.iwim.it\/wp-content\/uploads\/2026\/06\/Immagine-2026-06-17-173336-1024x493.webp 1024w, https:\/\/www.iwim.it\/wp-content\/uploads\/2026\/06\/Immagine-2026-06-17-173336-300x145.webp 300w, https:\/\/www.iwim.it\/wp-content\/uploads\/2026\/06\/Immagine-2026-06-17-173336-768x370.webp 768w, https:\/\/www.iwim.it\/wp-content\/uploads\/2026\/06\/Immagine-2026-06-17-173336-1536x740.webp 1536w, https:\/\/www.iwim.it\/wp-content\/uploads\/2026\/06\/Immagine-2026-06-17-173336.webp 1903w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f49503d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f49503d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-18103fe\" data-id=\"18103fe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69a3bac elementor-widget elementor-widget-heading\" data-id=\"69a3bac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Donn\u00e9es plus d\u00e9taill\u00e9es et pr\u00e9cises pour chaque v\u00e9hicule  <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a8715a elementor-widget elementor-widget-text-editor\" data-id=\"1a8715a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"PDq2pG_selectionAnchorContainer\" data-start=\"4756\" data-end=\"4823\">La vue d\u00e9taill\u00e9e du v\u00e9hicule a \u00e9t\u00e9 encore am\u00e9lior\u00e9e.<\/p><p data-start=\"4825\" data-end=\"5022\">En s\u00e9lectionnant un transit, l\u2019utilisateur peut ouvrir une fen\u00eatre d\u00e9di\u00e9e contenant la configuration compl\u00e8te des axes, les distances entre les axes et la charge mesur\u00e9e sur chaque axe ou groupe d\u2019axes.<\/p><p data-start=\"5024\" data-end=\"5180\"><strong data-start=\"5024\" data-end=\"5180\">Cette fonction vous permet de comprendre non seulement le poids total du v\u00e9hicule, mais aussi la mani\u00e8re dont la charge est r\u00e9partie le long de sa structure.<\/strong><\/p><p data-start=\"5182\" data-end=\"5229\">La visualisation est particuli\u00e8rement utile pour :  <\/p><ul data-start=\"5231\" data-end=\"5417\"><li data-section-id=\"319ams\" data-start=\"5231\" data-end=\"5249\">v\u00e9hicules lourds ;<\/li><li data-section-id=\"x7yl5m\" data-start=\"5250\" data-end=\"5287\">v\u00e9hicules aux configurations complexes ;<\/li><li data-section-id=\"c2anlt\" data-start=\"5288\" data-end=\"5312\">un transport exceptionnel ;<\/li><li data-section-id=\"tntwzp\" data-start=\"5313\" data-end=\"5335\">des charges d\u00e9s\u00e9quilibr\u00e9es ;<\/li><li data-section-id=\"1fubjnt\" data-start=\"5336\" data-end=\"5378\">transits en conditions de surcharge ;<\/li><li data-section-id=\"1wdvmgz\" data-start=\"5379\" data-end=\"5417\">Analyses \u00e0 la suite d\u2019\u00e9v\u00e9nements anormaux.<\/li><\/ul><p> <\/p><p data-start=\"5419\" data-end=\"5562\">Cela permet \u00e0 l\u2019op\u00e9rateur de passer rapidement de la vue g\u00e9n\u00e9rale du trafic \u00e0 l\u2019analyse d\u00e9taill\u00e9e d\u2019un v\u00e9hicule sp\u00e9cifique.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f14df7 elementor-widget elementor-widget-heading\" data-id=\"4f14df7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Surveillance plus d\u00e9taill\u00e9e des v\u00e9hicules lourds et exceptionnels<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-743a152 elementor-widget elementor-widget-image\" data-id=\"743a152\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"384\" src=\"https:\/\/www.iwim.it\/wp-content\/uploads\/2026\/06\/Immagine-2026-06-17-173603-1024x492.webp\" class=\"attachment-large size-large wp-image-14712\" alt=\"Capture d\u2019\u00e9cran de la vue d\u00e9taill\u00e9e BISON d\u2019un v\u00e9hicule lourd \u00e0 8 essieux pesant 100600 kg, vitesse 58 km\/h, direction est, surcharge de 128,6 % et charges r\u00e9parties sur les essieux individuels.\" srcset=\"https:\/\/www.iwim.it\/wp-content\/uploads\/2026\/06\/Immagine-2026-06-17-173603-1024x492.webp 1024w, https:\/\/www.iwim.it\/wp-content\/uploads\/2026\/06\/Immagine-2026-06-17-173603-300x144.webp 300w, https:\/\/www.iwim.it\/wp-content\/uploads\/2026\/06\/Immagine-2026-06-17-173603-768x369.webp 768w, https:\/\/www.iwim.it\/wp-content\/uploads\/2026\/06\/Immagine-2026-06-17-173603-1536x739.webp 1536w, https:\/\/www.iwim.it\/wp-content\/uploads\/2026\/06\/Immagine-2026-06-17-173603.webp 1903w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c3f5e1 elementor-widget elementor-widget-heading\" data-id=\"4c3f5e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Analyse d\u00e9taill\u00e9e des charges par essieu :\n La vue pop-up met en avant un v\u00e9hicule \u00e0 8 essieux, affichant les charges sur les essieux individuels, les poids totaux et les indicateurs de surcharge.<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec506a5 elementor-widget elementor-widget-text-editor\" data-id=\"ec506a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La repr\u00e9sentation graphique de la configuration du v\u00e9hicule permet d\u2019identifier imm\u00e9diatement toute concentration de charge et d\u2019\u00e9valuer plus pr\u00e9cis\u00e9ment l\u2019impact possible des transports sur le bitume ou les infrastructures.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd5728a elementor-widget elementor-widget-heading\" data-id=\"fd5728a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Analyse en temps r\u00e9el de l\u2019intensit\u00e9 du trafic et de l\u2019impact de l\u2019ESAL<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6fd550e elementor-widget elementor-widget-heading\" data-id=\"6fd550e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Donn\u00e9es de trafic lourd pour prot\u00e9ger le bitume et les infrastructures<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bafc5a1 elementor-widget elementor-widget-text-editor\" data-id=\"bafc5a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"PDq2pG_selectionAnchorContainer\" data-start=\"294\" data-end=\"759\">La nouvelle interface permet de visualiser en temps r\u00e9el <strong data-start=\"357\" data-end=\"383\">l\u2019intensit\u00e9 du trafic<\/strong>, la r\u00e9partition des v\u00e9hicules entre les voies et les directions, la vitesse moyenne, la pr\u00e9sence de ralentissements et la valeur <strong data-start=\"498\" data-end=\"506\">ESAL<\/strong> associ\u00e9e aux transits. Cet indicateur <b>permet de transformer les charges v\u00e9hiculeuses d\u00e9tect\u00e9es en une valeur \u00e9quivalente utile pour comprendre dans quelle mesure le trafic,<\/b> en particulier le trafic lourd, <b>affecte le bitume et les infrastructures au fil du temps.<\/b> <\/p><p data-start=\"761\" data-end=\"1225\">En combinant <b>les donn\u00e9es de trafic, la classification des v\u00e9hicules, les poids mesur\u00e9s et l\u2019ESA<\/b>L, l\u2019op\u00e9rateur peut adapter sa strat\u00e9gie op\u00e9rationnelle plus rapidement. En pr\u00e9sence de congestion, d\u2019augmentation des v\u00e9hicules lourds, de valeurs \u00e9lev\u00e9es de charge \u00e9quivalente ou de conditions anormales, il est possible d\u2019intervenir sur la r\u00e9gulation des d\u00e9bits, des signaux, des itin\u00e9raires alternatifs et de la planification de la maintenance, sur la base de donn\u00e9es r\u00e9elles et \u00e0 jour. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7fb096c elementor-widget elementor-widget-heading\" data-id=\"7fb096c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Consultez l\u2019histoire compl\u00e8te des transits enregistr\u00e9s<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-becc0ea elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"becc0ea\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ad993bb\" data-id=\"ad993bb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c0d0595 elementor-widget elementor-widget-image\" data-id=\"c0d0595\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"383\" src=\"https:\/\/www.iwim.it\/wp-content\/uploads\/2026\/06\/Immagine-2026-06-17-173510-1024x490.webp\" class=\"attachment-large size-large wp-image-14710\" alt=\"Capture d\u2019\u00e9cran de la table historique de donn\u00e9es BISON avec la liste des v\u00e9hicules immatricul\u00e9s, poids jusqu\u2019\u00e0 plus de 100000 kg, 8 essieux, direction est ou ouest, vitesse, r\u00e9sultat OK ou NL et code d\u2019erreur.\" srcset=\"https:\/\/www.iwim.it\/wp-content\/uploads\/2026\/06\/Immagine-2026-06-17-173510-1024x490.webp 1024w, https:\/\/www.iwim.it\/wp-content\/uploads\/2026\/06\/Immagine-2026-06-17-173510-300x144.webp 300w, https:\/\/www.iwim.it\/wp-content\/uploads\/2026\/06\/Immagine-2026-06-17-173510-768x367.webp 768w, https:\/\/www.iwim.it\/wp-content\/uploads\/2026\/06\/Immagine-2026-06-17-173510-1536x735.webp 1536w, https:\/\/www.iwim.it\/wp-content\/uploads\/2026\/06\/Immagine-2026-06-17-173510.webp 1900w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a6c803e elementor-widget elementor-widget-text-editor\" data-id=\"a6c803e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"PDq2pG_selectionAnchorContainer\" data-start=\"6176\" data-end=\"6315\">La plateforme vous permet de consulter tous les transits pr\u00e9c\u00e9demment enregistr\u00e9s via une table ordonn\u00e9e et facilement consultable.<\/p><p data-start=\"6317\" data-end=\"6330\">Vous pouvez :<\/p><ul data-start=\"6332\" data-end=\"6529\"><li data-section-id=\"1gt92jy\" data-start=\"6332\" data-end=\"6351\">appliquer des filtres ;<\/li><li data-section-id=\"156pwob\" data-start=\"6352\" data-end=\"6375\">trier les r\u00e9sultats ;<\/li><li data-section-id=\"rgcgge\" data-start=\"6376\" data-end=\"6408\">rechercher un transit sp\u00e9cifique ;<\/li><li data-section-id=\"1hwbfwm\" data-start=\"6409\" data-end=\"6442\">comparer diff\u00e9rentes p\u00e9riodes ;<\/li><li data-section-id=\"5st51t\" data-start=\"6443\" data-end=\"6482\">identifier des v\u00e9hicules ou des \u00e9v\u00e9nements anormaux ;<\/li><li data-section-id=\"1gmj11f\" data-start=\"6483\" data-end=\"6529\">exportez les donn\u00e9es pour un traitement ult\u00e9rieur.<\/li><\/ul><div> <\/div><p data-start=\"6531\" data-end=\"6739\">Les informations peuvent \u00eatre export\u00e9es sous divers formats, notamment CSV, HTML et XLSX, ce qui facilite leur int\u00e9gration avec des t\u00e2ches administratives, des rapports internes, des syst\u00e8mes de contr\u00f4le ou des plateformes externes.<\/p><p class=\"PDq2pG_selectionAnchorContainer\" data-start=\"6798\" data-end=\"7026\">La vue tabulaire pr\u00e9sente les transits enregistr\u00e9s \u00e0 travers <strong>des champs consultables<\/strong> tels que l\u2019identification, la date et l\u2019heure, le poids, le nombre d\u2019essieux, la classe du v\u00e9hicule, la direction, la vitesse, le r\u00e9sultat de d\u00e9tection et tout code d\u2019erreur.<\/p><p class=\"PDq2pG_selectionAnchorContainer\" data-start=\"6798\" data-end=\"7026\">Cette fonction permet au client d\u2019utiliser le logiciel non seulement pour le contr\u00f4le en temps r\u00e9el, mais aussi comme <strong>une archive structur\u00e9e des informations collect\u00e9es durant toute la p\u00e9riode d\u2019exploitation.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4e797fc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4e797fc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8ffb5e0\" data-id=\"8ffb5e0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1df0b36 elementor-widget elementor-widget-heading\" data-id=\"1df0b36\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Transits routiers organis\u00e9s selon des rapports statistiques personnalis\u00e9s<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43ca972 elementor-widget elementor-widget-text-editor\" data-id=\"43ca972\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"PDq2pG_selectionAnchorContainer\" data-start=\"7359\" data-end=\"7535\">Le syst\u00e8me int\u00e8gre une section d\u00e9di\u00e9e au reporting statistique, gr\u00e2ce \u00e0 laquelle les donn\u00e9es collect\u00e9es peuvent \u00eatre transform\u00e9es en graphiques, tableaux et indicateurs synth\u00e9tiques.<\/p><p data-start=\"7537\" data-end=\"7662\">Le manager peut obtenir une image compl\u00e8te de la situation sur un intervalle de temps donn\u00e9, en analysant, par exemple :<\/p><ul data-start=\"7664\" data-end=\"7923\"><li data-section-id=\"rxh58z\" data-start=\"7664\" data-end=\"7698\">nombre total de transits ;<\/li><li data-section-id=\"10ual29\" data-start=\"7699\" data-end=\"7738\">r\u00e9partition des cat\u00e9gories de v\u00e9hicules ;<\/li><li data-section-id=\"67lut3\" data-start=\"7739\" data-end=\"7769\">l\u2019incidence des v\u00e9hicules lourds ;<\/li><li data-section-id=\"eunzm5\" data-start=\"7770\" data-end=\"7800\">tendance aux surcharges ;<\/li><li data-section-id=\"1j177od\" data-start=\"7801\" data-end=\"7833\">le poids total du trafic ;<\/li><li data-section-id=\"lst7r8\" data-start=\"7834\" data-end=\"7886\">la r\u00e9partition des transits par voie ou direction ;<\/li><li data-section-id=\"kzto63\" data-start=\"7887\" data-end=\"7923\">Changements de trafic au fil du temps.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33bafc6 elementor-widget elementor-widget-image\" data-id=\"33bafc6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"364\" src=\"https:\/\/www.iwim.it\/wp-content\/uploads\/2026\/06\/Immagine-2026-06-17-173529-1024x466.webp\" class=\"attachment-large size-large wp-image-14711\" alt=\"Capture d\u2019\u00e9cran d\u2019un rapport statistique BISON avec graphique circulaire sur la composition du trafic, le total des v\u00e9hicules immatricul\u00e9s, le pourcentage de v\u00e9hicules lourds et un tableau des registres par type de v\u00e9hicule.\" srcset=\"https:\/\/www.iwim.it\/wp-content\/uploads\/2026\/06\/Immagine-2026-06-17-173529-1024x466.webp 1024w, https:\/\/www.iwim.it\/wp-content\/uploads\/2026\/06\/Immagine-2026-06-17-173529-300x137.webp 300w, https:\/\/www.iwim.it\/wp-content\/uploads\/2026\/06\/Immagine-2026-06-17-173529-768x350.webp 768w, https:\/\/www.iwim.it\/wp-content\/uploads\/2026\/06\/Immagine-2026-06-17-173529-1536x699.webp 1536w, https:\/\/www.iwim.it\/wp-content\/uploads\/2026\/06\/Immagine-2026-06-17-173529.webp 1894w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5123aa elementor-widget elementor-widget-heading\" data-id=\"c5123aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Les rapports peuvent \u00eatre personnalis\u00e9s selon les besoins du client et les indicateurs consid\u00e9r\u00e9s comme les plus importants pour la gestion du r\u00e9seau.<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8945288 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8945288\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4908372\" data-id=\"4908372\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bdbcc77 elementor-widget elementor-widget-text-editor\" data-id=\"bdbcc77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"8131\" data-end=\"8280\">La page du rapport r\u00e9sume <strong>la composition du trafic \u00e0 travers des graphiques, des tableaux et le nombre total de v\u00e9hicules immatricul\u00e9s durant la p\u00e9riode s\u00e9lectionn\u00e9e.<\/strong><\/p><p><span style=\"font-size: 1rem;\">Le reporting permet de transformer la surveillance continue en documentation technique et manag\u00e9riale, renfor\u00e7ant la tra\u00e7abilit\u00e9 des d\u00e9cisions et offrant un soutien concret \u00e0 la planification des interventions.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ecfe6a elementor-widget elementor-widget-heading\" data-id=\"5ecfe6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Interface GRIFONE pour la surveillance structurelle<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9108f9c elementor-widget elementor-widget-heading\" data-id=\"9108f9c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Donn\u00e9es sur l\u2019infrastructure et sa r\u00e9ponse aux charges de trafic<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-034d3c0 elementor-widget elementor-widget-text-editor\" data-id=\"034d3c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"PDq2pG_selectionAnchorContainer\" data-start=\"8687\" data-end=\"8824\">Le tableau de bord GRIFONE est d\u00e9di\u00e9 \u00e0 la visualisation du comportement de l\u2019infrastructure sous l\u2019effet de v\u00e9hicules r\u00e9els en transit.<\/p><p data-start=\"8826\" data-end=\"8848\">L\u2019interface combine :<\/p><ul data-start=\"8850\" data-end=\"9167\"><li data-section-id=\"etqtbj\" data-start=\"8850\" data-end=\"8912\">repr\u00e9sentation graphique de la section du pont ou de la route ;<\/li><li data-section-id=\"7rpf0r\" data-start=\"8913\" data-end=\"8948\">l\u2019emplacement des capteurs install\u00e9s ;<\/li><li data-section-id=\"czwqv9\" data-start=\"8949\" data-end=\"8991\">l\u2019identification du v\u00e9hicule en transit ;<\/li><li data-section-id=\"1rwmonc\" data-start=\"8992\" data-end=\"9034\">poids total et configuration des essieux ;<\/li><li data-section-id=\"5lglnd\" data-start=\"9035\" data-end=\"9065\">vitesse et classe du v\u00e9hicule ;<\/li><li data-section-id=\"8tyr5c\" data-start=\"9066\" data-end=\"9101\">Tableaux de mesures structurelles ;<\/li><li data-section-id=\"1idjbkp\" data-start=\"9102\" data-end=\"9167\">comparaison temporelle entre la charge appliqu\u00e9e et la r\u00e9ponse de l\u2019\u0153uvre.<\/li><\/ul><p> <\/p><p data-start=\"9169\" data-end=\"9582\"><strong>GRIFONE int\u00e8gre un r\u00e9seau de capteurs optiques install\u00e9s sur la structure avec une plateforme logicielle d\u00e9di\u00e9e \u00e0 l\u2019acquisition, la visualisation et l\u2019analyse des donn\u00e9es<\/strong>.<\/p><p data-start=\"9169\" data-end=\"9582\">Selon la configuration de conception, le syst\u00e8me peut mesurer les d\u00e9formations, les inclinaisons, les vibrations, les d\u00e9placements, la temp\u00e9rature et d\u2019autres param\u00e8tres importants pour \u00e9valuer le comportement de l\u2019\u0153uvre.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8023115 elementor-widget elementor-widget-image\" data-id=\"8023115\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"433\" src=\"https:\/\/www.iwim.it\/wp-content\/uploads\/2026\/07\/Analisi-della-la-risposta-strutturale-corrispondente-alle-informazioni-sul-peso-del-singolo-transito-del-veicolo-pesante-768x433.webp\" class=\"attachment-medium_large size-medium_large wp-image-14715\" alt=\"Donn\u00e9es sur l\u2019infrastructure et sa r\u00e9ponse aux charges de trafic\" srcset=\"https:\/\/www.iwim.it\/wp-content\/uploads\/2026\/07\/Analisi-della-la-risposta-strutturale-corrispondente-alle-informazioni-sul-peso-del-singolo-transito-del-veicolo-pesante-768x433.webp 768w, https:\/\/www.iwim.it\/wp-content\/uploads\/2026\/07\/Analisi-della-la-risposta-strutturale-corrispondente-alle-informazioni-sul-peso-del-singolo-transito-del-veicolo-pesante-300x169.webp 300w, https:\/\/www.iwim.it\/wp-content\/uploads\/2026\/07\/Analisi-della-la-risposta-strutturale-corrispondente-alle-informazioni-sul-peso-del-singolo-transito-del-veicolo-pesante.webp 907w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2976bd7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2976bd7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ea54f44\" data-id=\"ea54f44\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a366ca1 elementor-widget elementor-widget-heading\" data-id=\"a366ca1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">La synchronisation temporelle entre BISON et GRIFONE permet de s\u00e9lectionner un v\u00e9hicule sp\u00e9cifique et d\u2019analyser la r\u00e9ponse structurelle correspondante.<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f659fe7 elementor-widget elementor-widget-text-editor\" data-id=\"f659fe7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"PDq2pG_selectionAnchorContainer\" data-start=\"9658\" data-end=\"9839\">Le tableau de bord relie les donn\u00e9es de poids des v\u00e9hicules aux r\u00e9ponses enregistr\u00e9es par les capteurs, vous offrant une vue claire du comportement de l\u2019infrastructure sous la charge de trafic.<\/p><p data-start=\"10152\" data-end=\"10205\">Cela est particuli\u00e8rement utile pour :<\/p><ul data-start=\"10207\" data-end=\"10539\"><li data-section-id=\"1cvpal\" data-start=\"10207\" data-end=\"10254\">ponts et viaducs soumis \u00e0 un trafic intensif ;<\/li><li data-section-id=\"1juso6\" data-start=\"10255\" data-end=\"10284\">infrastructures strat\u00e9giques ;<\/li><li data-section-id=\"byhmv2\" data-start=\"10285\" data-end=\"10331\">des travaux avec une documentation historique incompl\u00e8te ;<\/li><li data-section-id=\"ydoccy\" data-start=\"10332\" data-end=\"10368\">les acc\u00e8s aux ports et les axes logistiques ;<\/li><li data-section-id=\"craxa4\" data-start=\"10369\" data-end=\"10434\">des structures pour lesquelles la continuit\u00e9 du service est essentielle ;<\/li><li data-section-id=\"1bzldxv\" data-start=\"10435\" data-end=\"10473\">des projets de maintenance pr\u00e9dictive ;<\/li><li data-section-id=\"q4rsca\" data-start=\"10474\" data-end=\"10539\">validation et mise \u00e0 jour de mod\u00e8les num\u00e9riques et de jumeaux num\u00e9riques.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8fd35b7 elementor-widget elementor-widget-text-editor\" data-id=\"8fd35b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>La technologie de la fibre optique<\/strong> offre \u00e9galement d\u2019importants avantages applicatifs. Les capteurs sont passifs, ne n\u00e9cessitent pas d\u2019alimentation \u00e9lectrique au point de mesure et sont immunis\u00e9s contre les interf\u00e9rences \u00e9lectromagn\u00e9tiques. Le r\u00e9seau peut \u00eatre con\u00e7u de mani\u00e8re modulaire et \u00e9tendu au fil du temps selon la critique du travail et les objectifs de l\u2019op\u00e9rateur.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-651c549 elementor-widget elementor-widget-image\" data-id=\"651c549\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"452\" src=\"https:\/\/www.iwim.it\/wp-content\/uploads\/2026\/07\/I-parametri-del-comportamento-strutturale-dellinfrastruttura-con-grafici-chiari-e-aggiornati-nel-tempo.-Sensori-in-Fibra-ottica-1024x578.png\" class=\"attachment-large size-large wp-image-14714\" alt=\"L\u2019interface de GRIFONE permet de visualiser les principaux param\u00e8tres du comportement structurel de l\u2019infrastructure en un seul \u00e9cran, avec des graphiques clairs mis \u00e0 jour au fil du temps. En particulier, le syst\u00e8me collecte et repr\u00e9sente des donn\u00e9es provenant de jauges de contrainte, d\u2019inclinom\u00e8tres, de capteurs de hauteur de tablier et de temp\u00e9rature, offrant \u00e0 l\u2019op\u00e9rateur une lecture imm\u00e9diate de l\u2019\u00e9volution du travail sous l\u2019effet des charges et des conditions environnementales. Cette organisation des donn\u00e9es facilite la d\u00e9tection des variations, anomalies et tendances, en soutenant une surveillance continue et une \u00e9valuation plus \u00e9clair\u00e9e de l\u2019\u00e9tat de l\u2019infrastructure.\" srcset=\"https:\/\/www.iwim.it\/wp-content\/uploads\/2026\/07\/I-parametri-del-comportamento-strutturale-dellinfrastruttura-con-grafici-chiari-e-aggiornati-nel-tempo.-Sensori-in-Fibra-ottica-1024x578.png 1024w, https:\/\/www.iwim.it\/wp-content\/uploads\/2026\/07\/I-parametri-del-comportamento-strutturale-dellinfrastruttura-con-grafici-chiari-e-aggiornati-nel-tempo.-Sensori-in-Fibra-ottica-300x169.png 300w, https:\/\/www.iwim.it\/wp-content\/uploads\/2026\/07\/I-parametri-del-comportamento-strutturale-dellinfrastruttura-con-grafici-chiari-e-aggiornati-nel-tempo.-Sensori-in-Fibra-ottica-768x434.png 768w, https:\/\/www.iwim.it\/wp-content\/uploads\/2026\/07\/I-parametri-del-comportamento-strutturale-dellinfrastruttura-con-grafici-chiari-e-aggiornati-nel-tempo.-Sensori-in-Fibra-ottica.png 1066w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a8c9c15 elementor-widget elementor-widget-text-editor\" data-id=\"a8c9c15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong data-start=\"17\" data-end=\"28\">L\u2019interface de GRIFONE<\/strong> permet de visualiser les principaux param\u00e8tres du comportement structurel de l\u2019infrastructure en un seul \u00e9cran, avec des graphiques clairs mis \u00e0 jour au fil du temps. En particulier, le syst\u00e8me collecte et repr\u00e9sente des donn\u00e9es provenant <strong data-start=\"266\" data-end=\"345\">de jauges de contrainte, d\u2019inclinom\u00e8tres, de capteurs de hauteur de tablier et de temp\u00e9rature<\/strong>, offrant \u00e0 l\u2019op\u00e9rateur une lecture imm\u00e9diate de l\u2019\u00e9volution du travail sous l\u2019effet des charges et des conditions environnementales. Cette organisation des donn\u00e9es facilite la d\u00e9tection des variations, anomalies et tendances, en soutenant une surveillance continue et une \u00e9valuation plus \u00e9clair\u00e9e de l\u2019\u00e9tat de l\u2019infrastructure.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-746bc2f elementor-widget elementor-widget-text-editor\" data-id=\"746bc2f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>BISON et GRIFONE offrent un \u00e9cosyst\u00e8me complet qui int\u00e8gre <strong data-start=\"61\" data-end=\"131\">pes\u00e9e dynamique, analyse du trafic et surveillance structurelle<\/strong> dans une plateforme intuitive, flexible et personnalisable.<\/p><p>Les donn\u00e9es sont clairement organis\u00e9es, consultables en temps r\u00e9el et facilement int\u00e9gr\u00e9es \u00e0 des syst\u00e8mes externes, afin de transformer des mesures complexes en informations v\u00e9ritablement utiles \u00e0 la gestion des infrastructures. Pour d\u00e9couvrir toutes les fonctionnalit\u00e9s du logiciel et \u00e9valuer comment l\u2019adapter aux besoins de votre projet, vous pouvez demander une d\u00e9monstration d\u00e9di\u00e9e. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-159f511 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"159f511\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.iwim.it\/fr\/nous-contacter\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contactez-nous pour essayer la nouvelle d\u00e9mo<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d972cbf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d972cbf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-394a952\" data-id=\"394a952\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-154347b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"154347b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-751c0f3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"751c0f3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dd820e4\" data-id=\"dd820e4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-038da13 elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-widget elementor-widget-portfolio\" data-id=\"038da13\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;columns&quot;:&quot;3&quot;,&quot;columns_tablet&quot;:&quot;2&quot;,&quot;columns_mobile&quot;:&quot;1&quot;,&quot;item_ratio&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0.66,&quot;sizes&quot;:[]},&quot;item_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"portfolio.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-portfolio elementor-grid elementor-posts-container\" role=\"list\">\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-14707 post type-post status-publish format-standard has-post-thumbnail hentry category-news tag-bison tag-certifications tag-fibres-optiques tag-pesage-dynamique tag-securite-routiere tag-wim-weigh-in-motion\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.iwim.it\/fr\/logiciel-integre-pour-surveiller-le-trafic-et-letat-des-infrastructures-avec-bison-et-grifone\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"145\" src=\"https:\/\/www.iwim.it\/wp-content\/uploads\/2026\/06\/Immagine-2026-06-17-173336-300x145.webp\" class=\"attachment-medium size-medium wp-image-14708\" alt=\"Capture d\u2019\u00e9cran du tableau de bord BISON en temps r\u00e9el avec les donn\u00e9es d\u2019un v\u00e9hicule l\u00e9ger : poids 2000 kg, vitesse 73 km\/h, 2 essieux, direction est, classe voiture\/fourgonnette et r\u00e9sultats NL.\" srcset=\"https:\/\/www.iwim.it\/wp-content\/uploads\/2026\/06\/Immagine-2026-06-17-173336-300x145.webp 300w, https:\/\/www.iwim.it\/wp-content\/uploads\/2026\/06\/Immagine-2026-06-17-173336-1024x493.webp 1024w, https:\/\/www.iwim.it\/wp-content\/uploads\/2026\/06\/Immagine-2026-06-17-173336-768x370.webp 768w, https:\/\/www.iwim.it\/wp-content\/uploads\/2026\/06\/Immagine-2026-06-17-173336-1536x740.webp 1536w, https:\/\/www.iwim.it\/wp-content\/uploads\/2026\/06\/Immagine-2026-06-17-173336.webp 1903w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tLogiciel int\u00e9gr\u00e9 pour surveiller le trafic et l\u2019\u00e9tat des infrastructures avec BISON et GRIFONE\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-10732 post type-post status-publish format-standard has-post-thumbnail hentry category-news\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.iwim.it\/fr\/histoire-pesage-dynamique-innovation\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"202\" src=\"https:\/\/www.iwim.it\/wp-content\/uploads\/2025\/03\/70-Anni-di-Innovazione-nella-Pesatura-Dinamica-Un-Viaggio-Tecnologico-per-Strade-Piu-Sicure-2-300x202.webp\" class=\"attachment-medium size-medium wp-image-11333\" alt=\"Chronologie de l&#039;\u00e9volution de la pes\u00e9e dynamique des v\u00e9hicules, des ann\u00e9es 1930 aux capteurs intelligents modernes.\" srcset=\"https:\/\/www.iwim.it\/wp-content\/uploads\/2025\/03\/70-Anni-di-Innovazione-nella-Pesatura-Dinamica-Un-Viaggio-Tecnologico-per-Strade-Piu-Sicure-2-300x202.webp 300w, https:\/\/www.iwim.it\/wp-content\/uploads\/2025\/03\/70-Anni-di-Innovazione-nella-Pesatura-Dinamica-Un-Viaggio-Tecnologico-per-Strade-Piu-Sicure-2-768x518.webp 768w, https:\/\/www.iwim.it\/wp-content\/uploads\/2025\/03\/70-Anni-di-Innovazione-nella-Pesatura-Dinamica-Un-Viaggio-Tecnologico-per-Strade-Piu-Sicure-2.webp 816w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\t70 ans d&rsquo;innovation dans le pesage dynamique !\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-11252 post type-post status-publish format-standard has-post-thumbnail hentry category-news\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.iwim.it\/fr\/iwim-securite-routiere-bisonte-thailande\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.iwim.it\/wp-content\/uploads\/2024\/11\/Guida_alla_Calibrazione-300x300.webp\" class=\"attachment-medium size-medium wp-image-9529\" alt=\"Guida alla calibrazione\" srcset=\"https:\/\/www.iwim.it\/wp-content\/uploads\/2024\/11\/Guida_alla_Calibrazione-300x300.webp 300w, https:\/\/www.iwim.it\/wp-content\/uploads\/2024\/11\/Guida_alla_Calibrazione-150x150.webp 150w, https:\/\/www.iwim.it\/wp-content\/uploads\/2024\/11\/Guida_alla_Calibrazione-768x768.webp 768w, https:\/\/www.iwim.it\/wp-content\/uploads\/2024\/11\/Guida_alla_Calibrazione.webp 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tiWiM : Syst\u00e8mes de Pesage Dynamique BISON \u00e0 Fibre Optique pour Am\u00e9liorer la S\u00e9curit\u00e9 Routi\u00e8re en Tha\u00eflande\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-10636 post type-post status-publish format-standard has-post-thumbnail hentry category-news\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.iwim.it\/fr\/bison-controle-basse-vitesse\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"199\" src=\"https:\/\/www.iwim.it\/wp-content\/uploads\/2025\/01\/BISONTE-LS-Control-300x199.jpg\" class=\"attachment-medium size-medium wp-image-9822\" alt=\"Sistema BISONTE LS Control installato su Strada\" srcset=\"https:\/\/www.iwim.it\/wp-content\/uploads\/2025\/01\/BISONTE-LS-Control-300x199.jpg 300w, https:\/\/www.iwim.it\/wp-content\/uploads\/2025\/01\/BISONTE-LS-Control-1024x678.jpg 1024w, https:\/\/www.iwim.it\/wp-content\/uploads\/2025\/01\/BISONTE-LS-Control-768x509.jpg 768w, https:\/\/www.iwim.it\/wp-content\/uploads\/2025\/01\/BISONTE-LS-Control-1536x1018.jpg 1536w, https:\/\/www.iwim.it\/wp-content\/uploads\/2025\/01\/BISONTE-LS-Control.jpg 1920w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tBISON: Modelo de Control de Baja Velocidad\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-10601 post type-post status-publish format-standard has-post-thumbnail hentry category-news\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.iwim.it\/fr\/pesage-dynamique-uruguay-2025\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.iwim.it\/wp-content\/uploads\/2025\/02\/N.12.1-300x300.webp\" class=\"attachment-medium size-medium wp-image-10388\" alt=\"CIEMSA and BISON staff at the end of the project\" srcset=\"https:\/\/www.iwim.it\/wp-content\/uploads\/2025\/02\/N.12.1-300x300.webp 300w, https:\/\/www.iwim.it\/wp-content\/uploads\/2025\/02\/N.12.1-1024x1024.webp 1024w, https:\/\/www.iwim.it\/wp-content\/uploads\/2025\/02\/N.12.1-150x150.webp 150w, https:\/\/www.iwim.it\/wp-content\/uploads\/2025\/02\/N.12.1-768x768.webp 768w, https:\/\/www.iwim.it\/wp-content\/uploads\/2025\/02\/N.12.1-1536x1536.webp 1536w, https:\/\/www.iwim.it\/wp-content\/uploads\/2025\/02\/N.12.1-scaled.webp 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tOuverture de 2025 avec une Nouvelle Installation de Pesage Dynamique en Uruguay\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>BISONTE &#038; GRIFONE pr\u00e9sentent une nouvelle d\u00e9monstration, plus claire et plus compl\u00e8te, con\u00e7ue pour montrer en un coup d\u2019\u0153il les donn\u00e9es de pes\u00e9e des v\u00e9hicules, l\u2019analyse du trafic et la surveillance structurelle des infrastructures.<\/p>\n","protected":false},"author":4,"featured_media":14708,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[21],"tags":[134,137,133,131,135,132],"class_list":["post-14707","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-bison","tag-certifications","tag-fibres-optiques","tag-pesage-dynamique","tag-securite-routiere","tag-wim-weigh-in-motion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BISON et GRIFONE : nouvelle d\u00e9monstration pour la pes\u00e9e et le suivi<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez la nouvelle d\u00e9mo BISON et GRIFONE pour la pes\u00e9e dynamique, l\u2019analyse du trafic, la d\u00e9tection de surcharge et la surveillance structurelle.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.iwim.it\/fr\/logiciel-integre-pour-surveiller-le-trafic-et-letat-des-infrastructures-avec-bison-et-grifone\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BISON et GRIFONE : nouvelle d\u00e9monstration pour la pes\u00e9e et le suivi\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez la nouvelle d\u00e9mo BISON et GRIFONE pour la pes\u00e9e dynamique, l\u2019analyse du trafic, la d\u00e9tection de surcharge et la surveillance structurelle.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.iwim.it\/fr\/logiciel-integre-pour-surveiller-le-trafic-et-letat-des-infrastructures-avec-bison-et-grifone\/\" \/>\n<meta property=\"og:site_name\" content=\"Bisonte by iWiM: weigh-in-motion\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-14T07:39:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T07:39:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.iwim.it\/wp-content\/uploads\/2026\/06\/Immagine-2026-06-17-173336.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1903\" \/>\n\t<meta property=\"og:image:height\" content=\"917\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"siteadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"siteadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.iwim.it\\\/fr\\\/logiciel-integre-pour-surveiller-le-trafic-et-letat-des-infrastructures-avec-bison-et-grifone\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.iwim.it\\\/fr\\\/logiciel-integre-pour-surveiller-le-trafic-et-letat-des-infrastructures-avec-bison-et-grifone\\\/\"},\"author\":{\"name\":\"siteadmin\",\"@id\":\"https:\\\/\\\/www.iwim.it\\\/fr\\\/#\\\/schema\\\/person\\\/d605d5c294d5a1a90b4874fde7932aa2\"},\"headline\":\"Logiciel int\u00e9gr\u00e9 pour surveiller le trafic et l\u2019\u00e9tat des infrastructures avec BISON et GRIFONE\",\"datePublished\":\"2026-07-14T07:39:19+00:00\",\"dateModified\":\"2026-07-14T07:39:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.iwim.it\\\/fr\\\/logiciel-integre-pour-surveiller-le-trafic-et-letat-des-infrastructures-avec-bison-et-grifone\\\/\"},\"wordCount\":2105,\"publisher\":{\"@id\":\"https:\\\/\\\/www.iwim.it\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.iwim.it\\\/fr\\\/logiciel-integre-pour-surveiller-le-trafic-et-letat-des-infrastructures-avec-bison-et-grifone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.iwim.it\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Immagine-2026-06-17-173336.webp\",\"keywords\":[\"Bison\",\"certifications\",\"fibres optiques\",\"pesage dynamique\",\"s\u00e9curit\u00e9 routi\u00e8re\",\"WIM (Weigh-in-Motion)\"],\"articleSection\":[\"News\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.iwim.it\\\/fr\\\/logiciel-integre-pour-surveiller-le-trafic-et-letat-des-infrastructures-avec-bison-et-grifone\\\/\",\"url\":\"https:\\\/\\\/www.iwim.it\\\/fr\\\/logiciel-integre-pour-surveiller-le-trafic-et-letat-des-infrastructures-avec-bison-et-grifone\\\/\",\"name\":\"BISON et GRIFONE : nouvelle d\u00e9monstration pour la pes\u00e9e et le suivi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.iwim.it\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.iwim.it\\\/fr\\\/logiciel-integre-pour-surveiller-le-trafic-et-letat-des-infrastructures-avec-bison-et-grifone\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.iwim.it\\\/fr\\\/logiciel-integre-pour-surveiller-le-trafic-et-letat-des-infrastructures-avec-bison-et-grifone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.iwim.it\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Immagine-2026-06-17-173336.webp\",\"datePublished\":\"2026-07-14T07:39:19+00:00\",\"dateModified\":\"2026-07-14T07:39:20+00:00\",\"description\":\"D\u00e9couvrez la nouvelle d\u00e9mo BISON et GRIFONE pour la pes\u00e9e dynamique, l\u2019analyse du trafic, la d\u00e9tection de surcharge et la surveillance structurelle.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.iwim.it\\\/fr\\\/logiciel-integre-pour-surveiller-le-trafic-et-letat-des-infrastructures-avec-bison-et-grifone\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.iwim.it\\\/fr\\\/logiciel-integre-pour-surveiller-le-trafic-et-letat-des-infrastructures-avec-bison-et-grifone\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.iwim.it\\\/fr\\\/logiciel-integre-pour-surveiller-le-trafic-et-letat-des-infrastructures-avec-bison-et-grifone\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.iwim.it\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Immagine-2026-06-17-173336.webp\",\"contentUrl\":\"https:\\\/\\\/www.iwim.it\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Immagine-2026-06-17-173336.webp\",\"width\":1903,\"height\":917,\"caption\":\"Le tableau de bord en temps r\u00e9el affiche les donn\u00e9es cl\u00e9s de transport en commun d\u2019un v\u00e9hicule l\u00e9ger, incluant le poids mesur\u00e9, la vitesse, le nombre d\u2019essieux, la direction, la classe du v\u00e9hicule et la valeur ESAL.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.iwim.it\\\/fr\\\/logiciel-integre-pour-surveiller-le-trafic-et-letat-des-infrastructures-avec-bison-et-grifone\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.iwim.it\\\/fr\\\/home-page\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Logiciel int\u00e9gr\u00e9 pour surveiller le trafic et l\u2019\u00e9tat des infrastructures avec BISON et GRIFONE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.iwim.it\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.iwim.it\\\/fr\\\/\",\"name\":\"Bisonte by iWiM: weigh-in-motion\",\"description\":\"Il sistema di pesatura dinamica\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.iwim.it\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.iwim.it\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.iwim.it\\\/fr\\\/#organization\",\"name\":\"iWiM\",\"url\":\"https:\\\/\\\/www.iwim.it\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.iwim.it\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.iwim.it\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/iwim.png\",\"contentUrl\":\"https:\\\/\\\/www.iwim.it\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/iwim.png\",\"width\":684,\"height\":684,\"caption\":\"iWiM\"},\"image\":{\"@id\":\"https:\\\/\\\/www.iwim.it\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/it.linkedin.com\\\/company\\\/iwim-srl\",\"https:\\\/\\\/www.youtube.com\\\/@iwimbison\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.iwim.it\\\/fr\\\/#\\\/schema\\\/person\\\/d605d5c294d5a1a90b4874fde7932aa2\",\"name\":\"siteadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1c3b32e81251512c3cdd4d6caa53dfb408e35b2852ef25b4b939b7c400e3e026?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1c3b32e81251512c3cdd4d6caa53dfb408e35b2852ef25b4b939b7c400e3e026?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1c3b32e81251512c3cdd4d6caa53dfb408e35b2852ef25b4b939b7c400e3e026?s=96&d=mm&r=g\",\"caption\":\"siteadmin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BISON et GRIFONE : nouvelle d\u00e9monstration pour la pes\u00e9e et le suivi","description":"D\u00e9couvrez la nouvelle d\u00e9mo BISON et GRIFONE pour la pes\u00e9e dynamique, l\u2019analyse du trafic, la d\u00e9tection de surcharge et la surveillance structurelle.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.iwim.it\/fr\/logiciel-integre-pour-surveiller-le-trafic-et-letat-des-infrastructures-avec-bison-et-grifone\/","og_locale":"fr_FR","og_type":"article","og_title":"BISON et GRIFONE : nouvelle d\u00e9monstration pour la pes\u00e9e et le suivi","og_description":"D\u00e9couvrez la nouvelle d\u00e9mo BISON et GRIFONE pour la pes\u00e9e dynamique, l\u2019analyse du trafic, la d\u00e9tection de surcharge et la surveillance structurelle.","og_url":"https:\/\/www.iwim.it\/fr\/logiciel-integre-pour-surveiller-le-trafic-et-letat-des-infrastructures-avec-bison-et-grifone\/","og_site_name":"Bisonte by iWiM: weigh-in-motion","article_published_time":"2026-07-14T07:39:19+00:00","article_modified_time":"2026-07-14T07:39:20+00:00","og_image":[{"width":1903,"height":917,"url":"https:\/\/www.iwim.it\/wp-content\/uploads\/2026\/06\/Immagine-2026-06-17-173336.webp","type":"image\/webp"}],"author":"siteadmin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"siteadmin","Dur\u00e9e de lecture estim\u00e9e":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.iwim.it\/fr\/logiciel-integre-pour-surveiller-le-trafic-et-letat-des-infrastructures-avec-bison-et-grifone\/#article","isPartOf":{"@id":"https:\/\/www.iwim.it\/fr\/logiciel-integre-pour-surveiller-le-trafic-et-letat-des-infrastructures-avec-bison-et-grifone\/"},"author":{"name":"siteadmin","@id":"https:\/\/www.iwim.it\/fr\/#\/schema\/person\/d605d5c294d5a1a90b4874fde7932aa2"},"headline":"Logiciel int\u00e9gr\u00e9 pour surveiller le trafic et l\u2019\u00e9tat des infrastructures avec BISON et GRIFONE","datePublished":"2026-07-14T07:39:19+00:00","dateModified":"2026-07-14T07:39:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.iwim.it\/fr\/logiciel-integre-pour-surveiller-le-trafic-et-letat-des-infrastructures-avec-bison-et-grifone\/"},"wordCount":2105,"publisher":{"@id":"https:\/\/www.iwim.it\/fr\/#organization"},"image":{"@id":"https:\/\/www.iwim.it\/fr\/logiciel-integre-pour-surveiller-le-trafic-et-letat-des-infrastructures-avec-bison-et-grifone\/#primaryimage"},"thumbnailUrl":"https:\/\/www.iwim.it\/wp-content\/uploads\/2026\/06\/Immagine-2026-06-17-173336.webp","keywords":["Bison","certifications","fibres optiques","pesage dynamique","s\u00e9curit\u00e9 routi\u00e8re","WIM (Weigh-in-Motion)"],"articleSection":["News"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.iwim.it\/fr\/logiciel-integre-pour-surveiller-le-trafic-et-letat-des-infrastructures-avec-bison-et-grifone\/","url":"https:\/\/www.iwim.it\/fr\/logiciel-integre-pour-surveiller-le-trafic-et-letat-des-infrastructures-avec-bison-et-grifone\/","name":"BISON et GRIFONE : nouvelle d\u00e9monstration pour la pes\u00e9e et le suivi","isPartOf":{"@id":"https:\/\/www.iwim.it\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.iwim.it\/fr\/logiciel-integre-pour-surveiller-le-trafic-et-letat-des-infrastructures-avec-bison-et-grifone\/#primaryimage"},"image":{"@id":"https:\/\/www.iwim.it\/fr\/logiciel-integre-pour-surveiller-le-trafic-et-letat-des-infrastructures-avec-bison-et-grifone\/#primaryimage"},"thumbnailUrl":"https:\/\/www.iwim.it\/wp-content\/uploads\/2026\/06\/Immagine-2026-06-17-173336.webp","datePublished":"2026-07-14T07:39:19+00:00","dateModified":"2026-07-14T07:39:20+00:00","description":"D\u00e9couvrez la nouvelle d\u00e9mo BISON et GRIFONE pour la pes\u00e9e dynamique, l\u2019analyse du trafic, la d\u00e9tection de surcharge et la surveillance structurelle.","breadcrumb":{"@id":"https:\/\/www.iwim.it\/fr\/logiciel-integre-pour-surveiller-le-trafic-et-letat-des-infrastructures-avec-bison-et-grifone\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.iwim.it\/fr\/logiciel-integre-pour-surveiller-le-trafic-et-letat-des-infrastructures-avec-bison-et-grifone\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.iwim.it\/fr\/logiciel-integre-pour-surveiller-le-trafic-et-letat-des-infrastructures-avec-bison-et-grifone\/#primaryimage","url":"https:\/\/www.iwim.it\/wp-content\/uploads\/2026\/06\/Immagine-2026-06-17-173336.webp","contentUrl":"https:\/\/www.iwim.it\/wp-content\/uploads\/2026\/06\/Immagine-2026-06-17-173336.webp","width":1903,"height":917,"caption":"Le tableau de bord en temps r\u00e9el affiche les donn\u00e9es cl\u00e9s de transport en commun d\u2019un v\u00e9hicule l\u00e9ger, incluant le poids mesur\u00e9, la vitesse, le nombre d\u2019essieux, la direction, la classe du v\u00e9hicule et la valeur ESAL."},{"@type":"BreadcrumbList","@id":"https:\/\/www.iwim.it\/fr\/logiciel-integre-pour-surveiller-le-trafic-et-letat-des-infrastructures-avec-bison-et-grifone\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.iwim.it\/fr\/home-page\/"},{"@type":"ListItem","position":2,"name":"Logiciel int\u00e9gr\u00e9 pour surveiller le trafic et l\u2019\u00e9tat des infrastructures avec BISON et GRIFONE"}]},{"@type":"WebSite","@id":"https:\/\/www.iwim.it\/fr\/#website","url":"https:\/\/www.iwim.it\/fr\/","name":"Bisonte by iWiM: weigh-in-motion","description":"Il sistema di pesatura dinamica","publisher":{"@id":"https:\/\/www.iwim.it\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.iwim.it\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.iwim.it\/fr\/#organization","name":"iWiM","url":"https:\/\/www.iwim.it\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.iwim.it\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.iwim.it\/wp-content\/uploads\/2023\/04\/iwim.png","contentUrl":"https:\/\/www.iwim.it\/wp-content\/uploads\/2023\/04\/iwim.png","width":684,"height":684,"caption":"iWiM"},"image":{"@id":"https:\/\/www.iwim.it\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/it.linkedin.com\/company\/iwim-srl","https:\/\/www.youtube.com\/@iwimbison"]},{"@type":"Person","@id":"https:\/\/www.iwim.it\/fr\/#\/schema\/person\/d605d5c294d5a1a90b4874fde7932aa2","name":"siteadmin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/1c3b32e81251512c3cdd4d6caa53dfb408e35b2852ef25b4b939b7c400e3e026?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1c3b32e81251512c3cdd4d6caa53dfb408e35b2852ef25b4b939b7c400e3e026?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1c3b32e81251512c3cdd4d6caa53dfb408e35b2852ef25b4b939b7c400e3e026?s=96&d=mm&r=g","caption":"siteadmin"}}]}},"_links":{"self":[{"href":"https:\/\/www.iwim.it\/fr\/wp-json\/wp\/v2\/posts\/14707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.iwim.it\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.iwim.it\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.iwim.it\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.iwim.it\/fr\/wp-json\/wp\/v2\/comments?post=14707"}],"version-history":[{"count":1,"href":"https:\/\/www.iwim.it\/fr\/wp-json\/wp\/v2\/posts\/14707\/revisions"}],"predecessor-version":[{"id":14716,"href":"https:\/\/www.iwim.it\/fr\/wp-json\/wp\/v2\/posts\/14707\/revisions\/14716"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.iwim.it\/fr\/wp-json\/wp\/v2\/media\/14708"}],"wp:attachment":[{"href":"https:\/\/www.iwim.it\/fr\/wp-json\/wp\/v2\/media?parent=14707"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.iwim.it\/fr\/wp-json\/wp\/v2\/categories?post=14707"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.iwim.it\/fr\/wp-json\/wp\/v2\/tags?post=14707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}